{"id":21813,"date":"2026-02-20T12:49:41","date_gmt":"2026-02-20T11:49:41","guid":{"rendered":"https:\/\/www.eim.com\/it\/?p=21813"},"modified":"2026-06-12T09:52:35","modified_gmt":"2026-06-12T07:52:35","slug":"integrazione-senza-interruzioni","status":"publish","type":"post","link":"https:\/\/www.eim.com\/it\/case-study\/integrazione-senza-interruzioni\/","title":{"rendered":"Integrazione Senza Interruzioni"},"content":{"rendered":"\n[et_pb_section fb_built=&#8221;1&#8243; custom_padding_last_edited=&#8221;on|phone&#8221; admin_label=&#8221;Hero Section&#8221; _builder_version=&#8221;4.27.5&#8243; background_color=&#8221;#002c3e&#8221; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_direction=&#8221;174deg&#8221; background_color_gradient_stops=&#8221;rgba(0,0,0,0.51) 87%|rgba(0,0,0,0.51) 87%&#8221; background_color_gradient_overlays_image=&#8221;on&#8221; background_color_gradient_start=&#8221;rgba(0,0,0,0.51)&#8221; background_color_gradient_start_position=&#8221;87%&#8221; background_color_gradient_end=&#8221;rgba(0,0,0,0.51)&#8221; background_color_gradient_end_position=&#8221;29%&#8221; background_image=&#8221;https:\/\/www.eim.com\/it\/wp-content\/uploads\/sites\/5\/2026\/02\/settore-fashion.webp&#8221; background_position=&#8221;top_center&#8221; min_height_tablet=&#8221;&#8221; min_height_phone=&#8221;720px&#8221; min_height_last_edited=&#8221;on|phone&#8221; height=&#8221;750px&#8221; height_tablet=&#8221;580px&#8221; height_phone=&#8221;auto&#8221; height_last_edited=&#8221;on|desktop&#8221; custom_padding=&#8221;4%||0%||false|false&#8221; custom_padding_tablet=&#8221;2%||0%||false|false&#8221; custom_padding_phone=&#8221;0%||0.2%||false|false&#8221; bottom_divider_style=&#8221;slant&#8221; bottom_divider_color=&#8221;#ffffff&#8221; bottom_divider_height=&#8221;150px&#8221; bottom_divider_flip=&#8221;horizontal&#8221; bottom_divider_height_tablet=&#8221;120px&#8221; bottom_divider_height_phone=&#8221;120px&#8221; bottom_divider_height_last_edited=&#8221;on|phone&#8221; background_last_edited=&#8221;on|phone&#8221; background_position_phone=&#8221;center_right&#8221; background_horizontal_offset_phone=&#8221;64%&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; background_color_gradient_direction__hover=&#8221;180deg&#8221; background_color_gradient_direction__hover_enabled=&#8221;180deg&#8221; background_color_gradient_start_position__hover=&#8221;0%&#8221; background_color_gradient_start_position__hover_enabled=&#8221;0%&#8221; background_color_gradient_end_position__hover=&#8221;100%&#8221; background_color_gradient_end_position__hover_enabled=&#8221;100%&#8221; background_color_gradient_stops__hover=&#8221;rgba(0,0,0,0.51) 0%|rgba(0,0,0,0.51) 100%&#8221;][et_pb_row custom_padding_last_edited=&#8221;on|desktop&#8221; _builder_version=&#8221;4.27.4&#8243; custom_margin=&#8221;||||false|false&#8221; custom_margin_tablet=&#8221;&#8221; custom_margin_phone=&#8221;0%||||false|false&#8221; custom_margin_last_edited=&#8221;on|phone&#8221; custom_padding=&#8221;2%||||false|false&#8221; custom_padding_tablet=&#8221;7%||||false|false&#8221; custom_padding_phone=&#8221;15%||9px||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_text content_tablet=&#8221;<h1><b>Visione e consenso sugli obiettivi aziendali: come velocizzare il cambiamento<\/b><\/h1>&#8221; content_phone=&#8221;<h1>Fondi di private equity: se si sceglie il manager sbagliato<\/h1>&#8221; content_last_edited=&#8221;off|desktop&#8221; admin_label=&#8221;Hero Section Title&#8221; _builder_version=&#8221;4.27.5&#8243; text_font=&#8221;Montserrat|800|||||||&#8221; text_font_size=&#8221;18px&#8221; text_line_height=&#8221;1.3em&#8221; header_font=&#8221;Montserrat|700|||||||&#8221; header_font_size=&#8221;56px&#8221; header_letter_spacing=&#8221;3px&#8221; header_line_height=&#8221;1.1em&#8221; header_2_font=&#8221;Montserrat|700|||||||&#8221; header_2_text_color=&#8221;rgba(255,255,255,0.6)&#8221; header_2_font_size=&#8221;90px&#8221; header_2_letter_spacing=&#8221;3px&#8221; header_2_line_height=&#8221;1.1em&#8221; text_orientation=&#8221;center&#8221; background_layout=&#8221;dark&#8221; max_width=&#8221;900px&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;0px||0px||false|false&#8221; custom_padding=&#8221;0px||||false|false&#8221; animation_direction=&#8221;bottom&#8221; header_font_size_tablet=&#8221;50px&#8221; header_font_size_phone=&#8221;20px&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; header_2_font_size_tablet=&#8221;&#8221; header_2_font_size_phone=&#8221;50px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; text_text_shadow_style=&#8221;preset1&#8243; text_text_shadow_horizontal_length=&#8221;0.28em&#8221; locked=&#8221;off&#8221; inline_fonts=&#8221;Prata,Montserrat&#8221; global_colors_info=&#8221;{}&#8221;]<h1>Integrazione Senza Interruzioni: Il Percorso verso una Struttura Unica e Solida<\/h1>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Montserrat|800|||||||&#8221; text_font_size=&#8221;26px&#8221; text_line_height=&#8221;1.3em&#8221; header_font=&#8221;Montserrat|700|||||||&#8221; header_font_size=&#8221;56px&#8221; header_letter_spacing=&#8221;3px&#8221; header_line_height=&#8221;1.1em&#8221; header_2_font=&#8221;Montserrat|700|||||||&#8221; header_2_text_color=&#8221;rgba(255,255,255,0.6)&#8221; header_2_font_size=&#8221;90px&#8221; header_2_letter_spacing=&#8221;3px&#8221; header_2_line_height=&#8221;1.1em&#8221; text_orientation=&#8221;center&#8221; background_layout=&#8221;dark&#8221; max_width=&#8221;80%&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;0px||0px||false|false&#8221; header_font_size_tablet=&#8221;56px&#8221; header_font_size_phone=&#8221;28px&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; header_2_font_size_tablet=&#8221;90px&#8221; header_2_font_size_phone=&#8221;50px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; text_text_shadow_style=&#8221;preset1&#8243; text_text_shadow_horizontal_length=&#8221;0.28em&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<p>FASHION &amp; APPAREL<\/p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.27.4&#8243; custom_margin=&#8221;||||false|false&#8221; custom_padding=&#8221;0%||0%||true|false&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;0px||0px||false|false&#8221; custom_padding=&#8221;0px||0px||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.5&#8243; text_font=&#8221;||||||||&#8221; text_font_size=&#8221;16px&#8221; header_font=&#8221;||||||||&#8221; max_width=&#8221;90%&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;3%|0px|3%|0px|false|false&#8221; custom_padding=&#8221;|2%|0px|2%|false|false&#8221; animation_direction=&#8221;left&#8221; hover_transition_duration=&#8221;0ms&#8221; global_colors_info=&#8221;{}&#8221;]<p>Un gruppo specializzato nella produzione di calzature iniettate in materiali termoplastici, PVC e gomma, acquisito nel 2012 da due fondi italiani di Private Equity, era articolato in quattro entit\u00e0 legali distinte che dovevano essere integrate in un\u2019unica societ\u00e0 in tempi brevi. L\u2019organizzazione necessitava di un rafforzamento urgente della funzione Finance per garantire continuit\u00e0 operativa e controllo durante la fase di transizione.<\/p>\n<p>In cinque mesi, un Partner EIM, affiancato da un PMO Consultant, ha supportato e supervisionato il programma guidato operativamente da un Interim CFO con piena responsabilit\u00e0 su Amministrazione Finanza e Controllo.<\/p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.27.5&#8243; text_font=&#8221;|700|on||||||&#8221; text_font_size=&#8221;16px&#8221; header_font=&#8221;||||||||&#8221; max_width=&#8221;90%&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;3%|0px|3%|0px|false|false&#8221; custom_padding=&#8221;|2%|0px|2%|false|false&#8221; animation_direction=&#8221;left&#8221; hover_transition_duration=&#8221;0ms&#8221; global_colors_info=&#8221;{}&#8221;]<p>Obiettivo: garantire continuit\u00e0 e presidio della funzione Finance, assicurare una governance solida e allineare i processi di reporting ai requisiti dei fondi di Private Equity in vista della nomina di un CFO permanente.\u00a0<span class=\"NormalTextRun SCXW164340683 BCX0\" style=\"font-size: 16px\"><\/span><\/p>\n<p><span class=\"NormalTextRun SCXW164340683 BCX0\" style=\"font-size: 16px\"><\/span><\/p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.27.4&#8243; text_font=&#8221;Montserrat|700|||||||&#8221; text_text_color=&#8221;#002c3e&#8221; text_font_size=&#8221;30px&#8221; header_font=&#8221;||||||||&#8221; header_2_font_size=&#8221;28px&#8221; max_width=&#8221;90%&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;|0px||0px|false|false&#8221; custom_padding=&#8221;2%|2%|0px|2%|false|false&#8221; custom_padding_tablet=&#8221;2%|2%|0px|2%|false|false&#8221; custom_padding_phone=&#8221;10%|2%|0px|2%|false|false&#8221; custom_padding_last_edited=&#8221;on|phone&#8221; animation_direction=&#8221;left&#8221; hover_transition_duration=&#8221;0ms&#8221; header_2_font_size_tablet=&#8221;28px&#8221; header_2_font_size_phone=&#8221;25px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;]<h2 style=\"text-align: center\">Le azioni intraprese da EIM<\/h2>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.27.5&#8243; text_font=&#8221;||||||||&#8221; text_font_size=&#8221;16px&#8221; header_font=&#8221;||||||||&#8221; max_width=&#8221;90%&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;3%|0px|3%|0px|false|false&#8221; custom_padding=&#8221;|2%|0px|2%|false|false&#8221; animation_direction=&#8221;left&#8221; hover_transition_duration=&#8221;0ms&#8221; global_colors_info=&#8221;{}&#8221;]<p>La trasformazione \u00e8 iniziata con la nomina dell\u2019Interim CFO che ha accompagnato il management nella fusione delle quattro entit\u00e0 legali in un\u2019unica struttura, assicurando la coerenza dei dati contabili e la corretta gestione delle interfacce contabili di sistema. Parallelamente, sono stati definiti processi di, reporting affidabili e puntuali; conto economico, stato patrimoniale e tesoreria pienamente coerenti con le direttive degli azionisti.<\/p>\n<p>\u00c8 stata inoltre rafforzata la governance finanziaria, garantendo reporting periodico accurato per il management e gli stakeholder.<\/p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.27.4&#8243; text_font=&#8221;Montserrat|700|||||||&#8221; text_text_color=&#8221;#002c3e&#8221; text_font_size=&#8221;30px&#8221; header_font=&#8221;||||||||&#8221; header_2_font_size=&#8221;28px&#8221; max_width=&#8221;90%&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;|0px||0px|false|false&#8221; custom_padding=&#8221;2%|2%|0px|2%|false|false&#8221; custom_padding_tablet=&#8221;2%|2%|0px|2%|false|false&#8221; custom_padding_phone=&#8221;10%|2%|0px|2%|false|false&#8221; custom_padding_last_edited=&#8221;on|phone&#8221; animation_direction=&#8221;left&#8221; hover_transition_duration=&#8221;0ms&#8221; header_2_font_size_tablet=&#8221;28px&#8221; header_2_font_size_phone=&#8221;25px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;]<h2 style=\"text-align: center\">I risultati ottenuti<\/h2>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.27.5&#8243; text_font=&#8221;||||||||&#8221; text_font_size=&#8221;16px&#8221; header_font=&#8221;||||||||&#8221; max_width=&#8221;90%&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;3%|0px|3%|0px|false|false&#8221; custom_padding=&#8221;|2%|0px|2%|false|false&#8221; animation_direction=&#8221;left&#8221; hover_transition_duration=&#8221;0ms&#8221; global_colors_info=&#8221;{}&#8221;]<ul>\n<li>Completamento della fusione delle quattro entit\u00e0 legali in un\u2019unica struttura;<\/li>\n<li>Consolidamento di un reporting finanziario puntuale e conforme ai requisiti degli azionisti;<\/li>\n<li>Rafforzamento della governance con maggiore affidabilit\u00e0 del reporting periodico;<\/li>\n<li>Posizionamento del Gruppo per la successiva fase di crescita con una struttura finanziaria pi\u00f9 robusta.<\/li>\n<\/ul>\n<p>Il progetto si \u00e8 concluso con una funzione Finance stabilizzata, processi integrati e una governance coerente con le aspettative dei fondi di investimento, preparando il terreno per l\u2019ingresso del CFO permanente.<\/p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; custom_padding_last_edited=&#8221;on|tablet&#8221; _builder_version=&#8221;4.27.4&#8243; background_color=&#8221;#002c3e&#8221; custom_margin=&#8221;||||false|false&#8221; custom_padding=&#8221;7em||0px||false|false&#8221; custom_padding_tablet=&#8221;10%||0px||false|false&#8221; custom_padding_phone=&#8221;26%||||false|false&#8221; top_divider_style=&#8221;slant&#8221; top_divider_color=&#8221;#FFFFFF&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row column_structure=&#8221;1_2,1_2&#8243; make_equal=&#8221;on&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_css_main_element=&#8221;display: flex; ||flex-direction:column; ||justify-content: space-between; &#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.4&#8243; text_font=&#8221;Montserrat|700|||||||&#8221; text_text_color=&#8221;#002c3e&#8221; text_font_size=&#8221;30px&#8221; header_font=&#8221;||||||||&#8221; header_2_text_color=&#8221;#FFFFFF&#8221; header_2_font_size=&#8221;22px&#8221; header_3_text_color=&#8221;#FFFFFF&#8221; max_width=&#8221;90%&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;|0px||0px|false|false&#8221; custom_padding=&#8221;0%|2%|0px|2%|false|false&#8221; animation_direction=&#8221;left&#8221; hover_transition_duration=&#8221;0ms&#8221; global_colors_info=&#8221;{}&#8221;]<h2 style=\"text-align: center\">Contatta il Partner di riferimento per questo progetto<\/h2>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.27.5&#8243; text_font=&#8221;||||||||&#8221; text_text_color=&#8221;#FFFFFF&#8221; text_font_size=&#8221;16px&#8221; header_font=&#8221;||||||||&#8221; max_width=&#8221;90%&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;3%|0px|3%|0px|false|false&#8221; custom_padding=&#8221;|2%|0px|2%|false|false&#8221; animation_direction=&#8221;left&#8221; hover_transition_duration=&#8221;0ms&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<p style=\"text-align: center\">???? <strong>Email<\/strong>: <a href=\"mailto:m.percopo@eim.com\">m.percopo@eim.com<\/a><\/p>\n<p style=\"text-align: center\"><strong>Ruolo<\/strong>: Client Partner EIM<\/p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/www.eim.com\/it\/wp-content\/uploads\/sites\/5\/2024\/02\/LinkedIn_logo_EIM_website.png&#8221; title_text=&#8221;LinkedIn_logo_EIM_website&#8221; url=&#8221;https:\/\/www.linkedin.com\/in\/percopo&#8221; align=&#8221;center&#8221; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; width=&#8221;3em&#8221; module_alignment=&#8221;center&#8221; hover_enabled=&#8221;0&#8243; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_css_main_element=&#8221;display: flex; ||flex-direction:column; ||justify-content: space-between; &#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.4&#8243; text_font=&#8221;Montserrat|700|||||||&#8221; text_text_color=&#8221;#002c3e&#8221; text_font_size=&#8221;30px&#8221; header_font=&#8221;||||||||&#8221; header_2_text_color=&#8221;#FFFFFF&#8221; header_2_font_size=&#8221;22px&#8221; header_3_text_color=&#8221;#FFFFFF&#8221; max_width=&#8221;90%&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;|0px||0px|false|false&#8221; custom_padding=&#8221;0%|2%|0px|2%|false|false&#8221; custom_padding_tablet=&#8221;0%|2%|0px|2%|false|false&#8221; custom_padding_phone=&#8221;10%|2%|0px|2%|false|false&#8221; custom_padding_last_edited=&#8221;on|phone&#8221; animation_direction=&#8221;left&#8221; hover_transition_duration=&#8221;0ms&#8221; global_colors_info=&#8221;{}&#8221;]<h2 style=\"text-align: center\">Contatta l&#8217;esperto di settore<\/h2>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.27.5&#8243; text_font=&#8221;||||||||&#8221; text_text_color=&#8221;#FFFFFF&#8221; text_font_size=&#8221;16px&#8221; header_font=&#8221;||||||||&#8221; max_width=&#8221;90%&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;3%|0px|3%|0px|false|false&#8221; custom_padding=&#8221;|2%|0px|2%|false|false&#8221; animation_direction=&#8221;left&#8221; hover_transition_duration=&#8221;0ms&#8221; hover_enabled=&#8221;0&#8243; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<p style=\"text-align: center;\">???? <strong>Email<\/strong>: <a href=\"mailto:d.scacchetti@eim.com\">d.scacchetti@eim.com<\/a><\/p>\n<p style=\"text-align: center;\"><strong>Ruolo<\/strong>: Partner EIM<\/p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/www.eim.com\/it\/wp-content\/uploads\/sites\/5\/2024\/02\/LinkedIn_logo_EIM_website.png&#8221; title_text=&#8221;LinkedIn_logo_EIM_website&#8221; url=&#8221;https:\/\/www.linkedin.com\/in\/dario-scacchetti-8bb35a&#8221; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; width=&#8221;3em&#8221; module_alignment=&#8221;center&#8221; hover_enabled=&#8221;0&#8243; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; custom_padding_last_edited=&#8221;on|desktop&#8221; _builder_version=&#8221;4.27.4&#8243; background_color=&#8221;#DB9300&#8243; custom_margin=&#8221;||||false|false&#8221; custom_padding=&#8221;5%||||false|false&#8221; custom_padding_tablet=&#8221;10%||||false|false&#8221; custom_padding_phone=&#8221;15%||||false|false&#8221; top_divider_style=&#8221;slant&#8221; top_divider_color=&#8221;#002c3e&#8221; top_divider_flip=&#8221;vertical&#8221; bottom_divider_color=&#8221;#ffffff&#8221; bottom_divider_flip=&#8221;horizontal&#8221; saved_tabs=&#8221;all&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; custom_margin=&#8221;-46px|auto||auto||&#8221; custom_padding=&#8221;105px||2px|||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_text admin_label=&#8221;Title&#8221; _builder_version=&#8221;4.27.4&#8243; text_font=&#8221;||||||||&#8221; text_text_color=&#8221;#FFFFFF&#8221; header_font=&#8221;Prata||||||||&#8221; header_2_font=&#8221;Montserrat|700|||||||&#8221; header_2_text_align=&#8221;center&#8221; header_2_font_size=&#8221;30px&#8221; header_3_text_color=&#8221;#FFFFFF&#8221; custom_margin=&#8221;||5px|&#8221; custom_padding=&#8221;||0px|||&#8221; animation_direction=&#8221;top&#8221; inline_fonts=&#8221;Prata,Montserrat&#8221; global_colors_info=&#8221;{}&#8221;]<h3 style=\"text-align: center\">Hai una sfida da proporci?<\/h3>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; text_text_color=&#8221;#FFFFFF&#8221; text_font_size=&#8221;18px&#8221; global_colors_info=&#8221;{}&#8221;]<p style=\"text-align: center\"><span>Troviamo insieme la soluzione che stai cercando, in pochi giorni.<\/span><\/p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.27.4&#8243; custom_margin=&#8221;20px||||false|false&#8221; custom_padding=&#8221;0px|||||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_button button_url=&#8221;https:\/\/www.eim.com\/it\/contatti\/&#8221; button_text=&#8221;CONTATTACI&#8221; button_alignment=&#8221;center&#8221; button_alignment_tablet=&#8221;center&#8221; button_alignment_phone=&#8221;center&#8221; button_alignment_last_edited=&#8221;off|desktop&#8221; _builder_version=&#8221;4.27.4&#8243; background_layout=&#8221;dark&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section]\n","protected":false},"excerpt":{"rendered":"<p>Integrazione Senza Interruzioni: Il Percorso verso una Struttura Unica e SolidaFASHION &amp; APPARELUn gruppo specializzato nella produzione di calzature iniettate in materiali termoplastici, PVC e gomma, acquisito nel 2012 da due fondi italiani di Private Equity, era articolato in quattro entit\u00e0 legali distinte che dovevano essere integrate in un\u2019unica societ\u00e0 in tempi brevi. L\u2019organizzazione necessitava <a href=\"https:\/\/www.eim.com\/it\/case-study\/integrazione-senza-interruzioni\/\" class=\"more-link\" aria-label=\"Read more: Integrazione Senza Interruzioni\">Read More<\/a><\/p>\n","protected":false},"author":2,"featured_media":21506,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"2880","footnotes":""},"categories":[2210],"tags":[2215],"class_list":["post-21813","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-case-study","tag-fashion"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Integrazione Senza Interruzioni - EIM ITALIA<\/title>\n<meta name=\"description\" content=\"Case study Fashion &amp; Apparel: il percorso verso una struttura unica e solida per un gruppo della produzione di calzature iniettate.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.eim.com\/it\/case-study\/integrazione-senza-interruzioni\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Integrazione Senza Interruzioni\" \/>\n<meta property=\"og:description\" content=\"Case study Fashion &amp; Apparel: il percorso verso una struttura unica e solida per un gruppo della produzione di calzature iniettate.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.eim.com\/it\/case-study\/integrazione-senza-interruzioni\/\" \/>\n<meta property=\"og:site_name\" content=\"EIM Italia\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-20T11:49:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-12T07:52:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.eim.com\/it\/wp-content\/uploads\/sites\/5\/2026\/02\/settore-fashion.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"eimworld\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"eimworld\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.eim.com\\\/it\\\/case-study\\\/integrazione-senza-interruzioni\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eim.com\\\/it\\\/case-study\\\/integrazione-senza-interruzioni\\\/\"},\"author\":{\"name\":\"eimworld\",\"@id\":\"https:\\\/\\\/www.eim.com\\\/it\\\/#\\\/schema\\\/person\\\/5aa1a797494ff2c5ee0721dc313c72e7\"},\"headline\":\"Integrazione Senza Interruzioni\",\"datePublished\":\"2026-02-20T11:49:41+00:00\",\"dateModified\":\"2026-06-12T07:52:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.eim.com\\\/it\\\/case-study\\\/integrazione-senza-interruzioni\\\/\"},\"wordCount\":2046,\"publisher\":{\"@id\":\"https:\\\/\\\/www.eim.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eim.com\\\/it\\\/case-study\\\/integrazione-senza-interruzioni\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.eim.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/02\\\/settore-fashion.webp\",\"keywords\":[\"fashion\"],\"articleSection\":[\"Case Study\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.eim.com\\\/it\\\/case-study\\\/integrazione-senza-interruzioni\\\/\",\"url\":\"https:\\\/\\\/www.eim.com\\\/it\\\/case-study\\\/integrazione-senza-interruzioni\\\/\",\"name\":\"Integrazione Senza Interruzioni - EIM ITALIA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eim.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.eim.com\\\/it\\\/case-study\\\/integrazione-senza-interruzioni\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eim.com\\\/it\\\/case-study\\\/integrazione-senza-interruzioni\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.eim.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/02\\\/settore-fashion.webp\",\"datePublished\":\"2026-02-20T11:49:41+00:00\",\"dateModified\":\"2026-06-12T07:52:35+00:00\",\"description\":\"Case study Fashion & Apparel: il percorso verso una struttura unica e solida per un gruppo della produzione di calzature iniettate.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.eim.com\\\/it\\\/case-study\\\/integrazione-senza-interruzioni\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.eim.com\\\/it\\\/case-study\\\/integrazione-senza-interruzioni\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.eim.com\\\/it\\\/case-study\\\/integrazione-senza-interruzioni\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.eim.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/02\\\/settore-fashion.webp\",\"contentUrl\":\"https:\\\/\\\/www.eim.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/02\\\/settore-fashion.webp\",\"width\":1920,\"height\":1280,\"caption\":\"Settore Fashion\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.eim.com\\\/it\\\/case-study\\\/integrazione-senza-interruzioni\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.eim.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Integrazione Senza Interruzioni\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.eim.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.eim.com\\\/it\\\/\",\"name\":\"EIM Italia\",\"description\":\"Siamo gli inventori dell&#039;Executive Interim Management\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.eim.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.eim.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.eim.com\\\/it\\\/#organization\",\"name\":\"EIM Italia - Executive Interim Managers\",\"url\":\"https:\\\/\\\/www.eim.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.eim.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.eim.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/07\\\/EIM_logo_positive_HD.png\",\"contentUrl\":\"https:\\\/\\\/www.eim.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/07\\\/EIM_logo_positive_HD.png\",\"width\":1920,\"height\":649,\"caption\":\"EIM Italia - Executive Interim Managers\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eim.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/executive-interim-management\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@EIM_Italia\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.eim.com\\\/it\\\/#\\\/schema\\\/person\\\/5aa1a797494ff2c5ee0721dc313c72e7\",\"name\":\"eimworld\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/06dc2838cb0c066488cdb4b104beba474e6305a2d11cbb1fb7353f876daae9f3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/06dc2838cb0c066488cdb4b104beba474e6305a2d11cbb1fb7353f876daae9f3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/06dc2838cb0c066488cdb4b104beba474e6305a2d11cbb1fb7353f876daae9f3?s=96&d=mm&r=g\",\"caption\":\"eimworld\"},\"sameAs\":[\"https:\\\/\\\/www.eim.com\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Integrazione Senza Interruzioni - EIM ITALIA","description":"Case study Fashion & Apparel: il percorso verso una struttura unica e solida per un gruppo della produzione di calzature iniettate.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.eim.com\/it\/case-study\/integrazione-senza-interruzioni\/","og_locale":"it_IT","og_type":"article","og_title":"Integrazione Senza Interruzioni","og_description":"Case study Fashion & Apparel: il percorso verso una struttura unica e solida per un gruppo della produzione di calzature iniettate.","og_url":"https:\/\/www.eim.com\/it\/case-study\/integrazione-senza-interruzioni\/","og_site_name":"EIM Italia","article_published_time":"2026-02-20T11:49:41+00:00","article_modified_time":"2026-06-12T07:52:35+00:00","og_image":[{"width":1920,"height":1280,"url":"https:\/\/www.eim.com\/it\/wp-content\/uploads\/sites\/5\/2026\/02\/settore-fashion.webp","type":"image\/webp"}],"author":"eimworld","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"eimworld","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.eim.com\/it\/case-study\/integrazione-senza-interruzioni\/#article","isPartOf":{"@id":"https:\/\/www.eim.com\/it\/case-study\/integrazione-senza-interruzioni\/"},"author":{"name":"eimworld","@id":"https:\/\/www.eim.com\/it\/#\/schema\/person\/5aa1a797494ff2c5ee0721dc313c72e7"},"headline":"Integrazione Senza Interruzioni","datePublished":"2026-02-20T11:49:41+00:00","dateModified":"2026-06-12T07:52:35+00:00","mainEntityOfPage":{"@id":"https:\/\/www.eim.com\/it\/case-study\/integrazione-senza-interruzioni\/"},"wordCount":2046,"publisher":{"@id":"https:\/\/www.eim.com\/it\/#organization"},"image":{"@id":"https:\/\/www.eim.com\/it\/case-study\/integrazione-senza-interruzioni\/#primaryimage"},"thumbnailUrl":"https:\/\/www.eim.com\/it\/wp-content\/uploads\/sites\/5\/2026\/02\/settore-fashion.webp","keywords":["fashion"],"articleSection":["Case Study"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.eim.com\/it\/case-study\/integrazione-senza-interruzioni\/","url":"https:\/\/www.eim.com\/it\/case-study\/integrazione-senza-interruzioni\/","name":"Integrazione Senza Interruzioni - EIM ITALIA","isPartOf":{"@id":"https:\/\/www.eim.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.eim.com\/it\/case-study\/integrazione-senza-interruzioni\/#primaryimage"},"image":{"@id":"https:\/\/www.eim.com\/it\/case-study\/integrazione-senza-interruzioni\/#primaryimage"},"thumbnailUrl":"https:\/\/www.eim.com\/it\/wp-content\/uploads\/sites\/5\/2026\/02\/settore-fashion.webp","datePublished":"2026-02-20T11:49:41+00:00","dateModified":"2026-06-12T07:52:35+00:00","description":"Case study Fashion & Apparel: il percorso verso una struttura unica e solida per un gruppo della produzione di calzature iniettate.","breadcrumb":{"@id":"https:\/\/www.eim.com\/it\/case-study\/integrazione-senza-interruzioni\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.eim.com\/it\/case-study\/integrazione-senza-interruzioni\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.eim.com\/it\/case-study\/integrazione-senza-interruzioni\/#primaryimage","url":"https:\/\/www.eim.com\/it\/wp-content\/uploads\/sites\/5\/2026\/02\/settore-fashion.webp","contentUrl":"https:\/\/www.eim.com\/it\/wp-content\/uploads\/sites\/5\/2026\/02\/settore-fashion.webp","width":1920,"height":1280,"caption":"Settore Fashion"},{"@type":"BreadcrumbList","@id":"https:\/\/www.eim.com\/it\/case-study\/integrazione-senza-interruzioni\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.eim.com\/it\/"},{"@type":"ListItem","position":2,"name":"Integrazione Senza Interruzioni"}]},{"@type":"WebSite","@id":"https:\/\/www.eim.com\/it\/#website","url":"https:\/\/www.eim.com\/it\/","name":"EIM Italia","description":"Siamo gli inventori dell&#039;Executive Interim Management","publisher":{"@id":"https:\/\/www.eim.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.eim.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.eim.com\/it\/#organization","name":"EIM Italia - Executive Interim Managers","url":"https:\/\/www.eim.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.eim.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.eim.com\/it\/wp-content\/uploads\/sites\/5\/2026\/07\/EIM_logo_positive_HD.png","contentUrl":"https:\/\/www.eim.com\/it\/wp-content\/uploads\/sites\/5\/2026\/07\/EIM_logo_positive_HD.png","width":1920,"height":649,"caption":"EIM Italia - Executive Interim Managers"},"image":{"@id":"https:\/\/www.eim.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/executive-interim-management\/","https:\/\/www.youtube.com\/@EIM_Italia"]},{"@type":"Person","@id":"https:\/\/www.eim.com\/it\/#\/schema\/person\/5aa1a797494ff2c5ee0721dc313c72e7","name":"eimworld","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/06dc2838cb0c066488cdb4b104beba474e6305a2d11cbb1fb7353f876daae9f3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/06dc2838cb0c066488cdb4b104beba474e6305a2d11cbb1fb7353f876daae9f3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/06dc2838cb0c066488cdb4b104beba474e6305a2d11cbb1fb7353f876daae9f3?s=96&d=mm&r=g","caption":"eimworld"},"sameAs":["https:\/\/www.eim.com"]}]}},"_links":{"self":[{"href":"https:\/\/www.eim.com\/it\/wp-json\/wp\/v2\/posts\/21813","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eim.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.eim.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.eim.com\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eim.com\/it\/wp-json\/wp\/v2\/comments?post=21813"}],"version-history":[{"count":0,"href":"https:\/\/www.eim.com\/it\/wp-json\/wp\/v2\/posts\/21813\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.eim.com\/it\/wp-json\/wp\/v2\/media\/21506"}],"wp:attachment":[{"href":"https:\/\/www.eim.com\/it\/wp-json\/wp\/v2\/media?parent=21813"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.eim.com\/it\/wp-json\/wp\/v2\/categories?post=21813"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.eim.com\/it\/wp-json\/wp\/v2\/tags?post=21813"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}