{"id":73,"date":"2019-09-12T10:03:17","date_gmt":"2019-09-12T10:03:17","guid":{"rendered":"https:\/\/www.eim.com\/es\/faq\/"},"modified":"2026-06-12T07:40:27","modified_gmt":"2026-06-12T07:40:27","slug":"faq","status":"publish","type":"page","link":"https:\/\/www.eim.com\/es\/faq\/","title":{"rendered":"FAQ"},"content":{"rendered":"\n\n[et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Hero Section&#8221; _builder_version=&#8221;3.27.4&#8243; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_start=&#8221;rgba(0,0,0,0.4)&#8221; background_color_gradient_end=&#8221;rgba(0,0,0,0.4)&#8221; background_color_gradient_overlays_image=&#8221;on&#8221; background_image=&#8221;https:\/\/www.eim.com\/wp-content\/uploads\/2019\/10\/typing.jpeg&#8221; height=&#8221;520px&#8221; custom_padding=&#8221;6%||0%|||&#8221; bottom_divider_style=&#8221;slant&#8221; bottom_divider_color=&#8221;#ffffff&#8221; bottom_divider_height=&#8221;150px&#8221; bottom_divider_flip=&#8221;horizontal&#8221; saved_tabs=&#8221;all&#8221; fb_built=&#8221;1&#8243; background_color_gradient_direction__hover=&#8221;180deg&#8221; background_color_gradient_direction__hover_enabled=&#8221;180deg&#8221; background_color_gradient_start_position__hover=&#8221;0%&#8221; background_color_gradient_start_position__hover_enabled=&#8221;0%&#8221; background_color_gradient_end_position__hover=&#8221;100%&#8221; background_color_gradient_end_position__hover_enabled=&#8221;100%&#8221; _i=&#8221;0&#8243; _address=&#8221;0&#8243;][et_pb_row admin_label=&#8221;Page Title Area&#8221; _builder_version=&#8221;3.27.4&#8243; width=&#8221;100%&#8221; max_width=&#8221;2560px&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;-2%|auto|0px|auto|false|false&#8221; custom_padding=&#8221;0px|||||&#8221; _i=&#8221;0&#8243; _address=&#8221;0.0&#8243;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; _i=&#8221;0&#8243; _address=&#8221;0.0.0&#8243; custom_padding__hover=&#8221;|||&#8221;][et_pb_text admin_label=&#8221;Hero Section Title&#8221; _builder_version=&#8221;3.27.4&#8243; text_font=&#8221;Montserrat|800|||||||&#8221; text_font_size=&#8221;18px&#8221; text_line_height=&#8221;1.3em&#8221; text_text_shadow_style=&#8221;preset1&#8243; text_text_shadow_horizontal_length=&#8221;0.23em&#8221; header_font=&#8221;Montserrat|700|||||||&#8221; header_font_size=&#8221;56px&#8221; header_letter_spacing=&#8221;3px&#8221; header_line_height=&#8221;1.1em&#8221; header_2_font=&#8221;Montserrat|700|||||||&#8221; header_2_text_color=&#8221;rgba(255,255,255,0.6)&#8221; header_2_font_size=&#8221;90px&#8221; header_2_letter_spacing=&#8221;3px&#8221; header_2_line_height=&#8221;1.1em&#8221; text_orientation=&#8221;center&#8221; background_layout=&#8221;dark&#8221; max_width=&#8221;800px&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;0px||0px||false|false&#8221; animation_style=&#8221;fade&#8221; animation_direction=&#8221;bottom&#8221; animation_duration=&#8221;1350ms&#8221; header_font_size_phone=&#8221;28px&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; header_2_font_size_phone=&#8221;50px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; inline_fonts=&#8221;Prata,Montserrat&#8221; _i=&#8221;0&#8243; _address=&#8221;0.0.0.0&#8243;]\n<h1>Preguntas m\u00e1s habituales<\/h1>\n[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;3.27.4&#8243; custom_margin=&#8221;||8%||false|false&#8221; custom_padding=&#8221;0%||0%||true|false&#8221; saved_tabs=&#8221;all&#8221; fb_built=&#8221;1&#8243; _i=&#8221;1&#8243; _address=&#8221;1&#8243;][et_pb_row admin_label=&#8221;Title Area&#8221; _builder_version=&#8221;3.27.4&#8243; background_color=&#8221;rgba(0,0,0,0)&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;|370px||auto|false|false&#8221; custom_padding=&#8221;0px|0px|0px|0px|false|false&#8221; _i=&#8221;0&#8243; _address=&#8221;1.0&#8243;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; _i=&#8221;0&#8243; _address=&#8221;1.0.0&#8243; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;3.27.4&#8243; text_font=&#8221;Montserrat|700|||||||&#8221; text_text_color=&#8221;#002c3e&#8221; text_font_size=&#8221;25px&#8221; custom_margin=&#8221;8%|0px|||false|false&#8221; _i=&#8221;0&#8243; _address=&#8221;1.0.0.0&#8243;]\n<p style=\"text-align: center\">Qu\u00e9 hace a EIM \u00fanica y otras preguntas habituales<\/p>\n[\/et_pb_text][et_pb_text _builder_version=&#8221;3.27.4&#8243; _dynamic_attributes=&#8221;link_option_url&#8221; text_font=&#8221;||||||||&#8221; text_font_size=&#8221;16px&#8221; header_font=&#8221;||||||||&#8221; max_width=&#8221;90%&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;2.6%|0px|5%|0px|false|false&#8221; custom_padding=&#8221;|2%|70px|2%|false|false&#8221; animation_style=&#8221;flip&#8221; animation_direction=&#8221;left&#8221; animation_intensity_flip=&#8221;30%&#8221; animation_starting_opacity=&#8221;100%&#8221; link_option_url=&#8221;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjgiLCJlbmFibGVfaHRtbCI6Im9mZiJ9fQ==@&#8221; _i=&#8221;1&#8243; _address=&#8221;1.0.0.1&#8243;]\n<p style=\"text-align: center\">Si tiene alguna pregunta, por favor no dude en contactar con una de <a href=\"\/es\/oficinas\">nuestras oficinas<\/a> cercanas a Usted.<\/p>\n<p style=\"text-align: center\">Mientras tanto, mire estas preguntas, que otros potenciales clientes nos han hecho antes.<\/p>\n[\/et_pb_text][et_pb_toggle title=&#8221;\u00bfQu\u00e9 es el interim management? &#8221; open_toggle_text_color=&#8221;#002c3e&#8221; open_toggle_background_color=&#8221;#e6e6e6&#8243; closed_toggle_text_color=&#8221;#002c3e&#8221; closed_toggle_background_color=&#8221;#e6e6e6&#8243; _builder_version=&#8221;3.27.4&#8243; title_text_color=&#8221;#ffffff&#8221; _i=&#8221;2&#8243; _address=&#8221;1.0.0.2&#8243;]\n\nOtro t\u00e9rmino para ello ser\u00eda <strong>Direcci\u00f3n de Transici\u00f3n<\/strong>.\n\nSignifica que despu\u00e9s de que los ejecutivos hayan cumplido con \u00e9xito las tareas predefinidas con precisi\u00f3n, se marchar\u00e1n de la compa\u00f1\u00eda. Sin herir sentimientos, sin demandas judiciales ni periodo de preaviso. \u00bfPero por qu\u00e9 usted querr\u00e1 que una persona exitosa se vuelva a marchar? Bueno, alguien que fue la persona m\u00e1s adecuada para un reto espec\u00edfico, podr\u00eda no ser la persona adecuada para el siguiente reto, que todav\u00eda no ha surgido. Imag\u00ednese que pudiera recurrir constantemente a lo mejor de los dos mundos \u2013 mentes e ideas frescas y la mirada desde fuera, por un lado; pericia, experiencia y conocimiento de otros sectores o compa\u00f1\u00edas por el otro.\n\n[\/et_pb_toggle][et_pb_toggle title=&#8221;\u00bfCu\u00e1l es la diferencia respecto a la b\u00fasqueda de ejecutivos cl\u00e1sica?&#8221; open_toggle_text_color=&#8221;#002c3e&#8221; open_toggle_background_color=&#8221;#e6e6e6&#8243; closed_toggle_text_color=&#8221;#002c3e&#8221; closed_toggle_background_color=&#8221;#e6e6e6&#8243; _builder_version=&#8221;3.27.4&#8243; title_text_color=&#8221;#ffffff&#8221; _i=&#8221;3&#8243; _address=&#8221;1.0.0.3&#8243;]\n\nA diferencia de la b\u00fasqueda de ejecutivos que puede llevar varios meses, los interim managers est\u00e1n listos para comenzar en 1-3 semanas y necesitar\u00e1n un periodo de adaptaci\u00f3n de solo unos d\u00edas, debido a su gran experiencia.\n\nEllos ya hicieron todo esto antes.\n\nTan pronto como las tareas claramente predefinidas se hayan completado, dejar\u00e1n la compa\u00f1\u00eda y de causar gastos.\n\n[\/et_pb_toggle][et_pb_toggle title=&#8221;\u00bfQu\u00e9 diferencia EIM de sus competidores?&#8221; open_toggle_text_color=&#8221;#002c3e&#8221; open_toggle_background_color=&#8221;#e6e6e6&#8243; closed_toggle_text_color=&#8221;#002c3e&#8221; closed_toggle_background_color=&#8221;#e6e6e6&#8243; _builder_version=&#8221;3.27.4&#8243; title_text_color=&#8221;#ffffff&#8221; _i=&#8221;4&#8243; _address=&#8221;1.0.0.4&#8243;]\n\nEIM no est\u00e1 en el negocio de vender CVs.\n\nEn vez de eso, resolvemos retos de negocios aportando soluciones individuales con los expertos del sector adecuados.\n\nEIM ha acumulado una dilatada experiencia en sus 30 a\u00f1os de existencia y 10.000 proyectos y ha desarrollado una metodolog\u00eda acreditada de c\u00f3mo liderar la transformaci\u00f3n con \u00e9xito. Adem\u00e1s, no solo ofrecemos interim management para reaccionar ante emergencias o vacantes. En vez de eso ofrecemos una herramienta moderna de gesti\u00f3n para optimizar su compa\u00f1\u00eda de forma proactiva para el crecimiento, la eficiencia o la transformaci\u00f3n digital.\n\nEso significa que le ayudaremos a analizar qui\u00e9n aportar\u00e1 mayor valor a su compa\u00f1\u00eda en la situaci\u00f3n actual. Por otro lado, \u00bfpara qu\u00e9 sirve el mejor proceso o algoritmo de b\u00fasqueda, si empezamos con un perfil de b\u00fasqueda que no cubre completamente sus necesidades? La mayor\u00eda de nuestros competidores se salta este paso de definici\u00f3n del perfil.\n\nAdem\u00e1s, aseguraremos que nuestro interim manager comienza con una serie de objetivos y tareas claramente predefinidos y una estrategia expresamente comunicada.&nbsp; Eso es muy importante, porque de otra manera se perder\u00e1 tiempo y podr\u00e1n producirse disputas por las competencias. Adicionalmente, durante todo el proyecto, un Socio l\u00edder de EIM estar\u00e1 siempre disponible para garantizar una comunicaci\u00f3n fluida y transparente entre usted y el interim manager.\n\n[\/et_pb_toggle][et_pb_toggle title=&#8221;\u00bfCu\u00e1l es la funci\u00f3n de EIM durante un proyecto? &#8221; open_toggle_text_color=&#8221;#002c3e&#8221; open_toggle_background_color=&#8221;#e6e6e6&#8243; closed_toggle_text_color=&#8221;#002c3e&#8221; closed_toggle_background_color=&#8221;#e6e6e6&#8243; _builder_version=&#8221;3.27.4&#8243; title_text_color=&#8221;#ffffff&#8221; _i=&#8221;5&#8243; _address=&#8221;1.0.0.5&#8243;]\n\nEl asesor\/consejero de EIM es responsable de la preparaci\u00f3n del interim manager y es un punto de contacto de confianza competente para usted y el Interim Manager de EIM.\n\nLos asesores\/consejeros de EIM utilizan su gran experiencia en el sector y o situaci\u00f3n, resultado de trabajar muchos a\u00f1os en funciones de direcci\u00f3n y consultor\u00eda, as\u00ed como la metodolog\u00eda de EIM. Eso le aporta un valor a\u00f1adido real, que se complementa con una riqueza siempre creciente de experiencia en la gesti\u00f3n de proyectos y misiones de interim.\n\n[\/et_pb_toggle][et_pb_toggle title=&#8221;\u00bfC\u00f3mo asegura EIM la calidad de sus interim managers?&#8221; open_toggle_text_color=&#8221;#002c3e&#8221; open_toggle_background_color=&#8221;#e6e6e6&#8243; closed_toggle_text_color=&#8221;#002c3e&#8221; closed_toggle_background_color=&#8221;#e6e6e6&#8243; _builder_version=&#8221;3.27.4&#8243; title_text_color=&#8221;#ffffff&#8221; _i=&#8221;6&#8243; _address=&#8221;1.0.0.6&#8243;]\n\nEIM es extremadamente minucioso y honesto en la selecci\u00f3n de los interim managers. Todos los Interim Managers de EIM disponen de una extensa experiencia de direcci\u00f3n, piensan y act\u00faan en par\u00e1metros operativos y pragm\u00e1ticos y trabajan en plena colaboraci\u00f3n con el cliente desde el primer d\u00eda de la misi\u00f3n. Eso lo aseguramos mediante una evaluaci\u00f3n del historial de todos los miembros de nuestro pool de directivos, incluyendo entrevistas personales y una comprobaci\u00f3n de sus referencias, que no se externaliza o delega nunca, sino que realizan Socios de EIM.\n\n[\/et_pb_toggle][et_pb_toggle title=&#8221;\u00bfPor qu\u00e9 deber\u00eda confiar a EIM y sus ejecutivos mis problemas m\u00e1s delicados y confidenciales? &#8221; open_toggle_text_color=&#8221;#002c3e&#8221; open_toggle_background_color=&#8221;#e6e6e6&#8243; closed_toggle_text_color=&#8221;#002c3e&#8221; closed_toggle_background_color=&#8221;#e6e6e6&#8243; _builder_version=&#8221;3.27.4&#8243; title_text_color=&#8221;#ffffff&#8221; _i=&#8221;7&#8243; _address=&#8221;1.0.0.7&#8243;]\n\nEIM atiende este nivel de confianza con un alto grado de profesionalidad y act\u00faa de acuerdo con principios \u00e9ticos claros.\n\nNuestro \u00e9xito depende fuertemente de nuestra reputaci\u00f3n. Por lo tanto, nos interesa ser siempre un socio fiable para nuestros clientes y construir relaciones comerciales duraderas. Seg\u00fan nuestros n\u00fameros, lo hemos logrado.\n\n[\/et_pb_toggle][et_pb_toggle title=&#8221;\u00bfC\u00f3mo es su proceso? \u00bfQu\u00e9 pasar\u00e1 si les doy una oportunidad?&#8221; open_toggle_text_color=&#8221;#002c3e&#8221; open_toggle_background_color=&#8221;#e6e6e6&#8243; closed_toggle_text_color=&#8221;#002c3e&#8221; closed_toggle_background_color=&#8221;#e6e6e6&#8243; _builder_version=&#8221;3.27.4&#8243; title_text_color=&#8221;#ffffff&#8221; _i=&#8221;8&#8243; _address=&#8221;1.0.0.8&#8243;]\n\nPrimero pasaremos a comprender la situaci\u00f3n existente y la raz\u00f3n por la cual est\u00e1 buscando una soluci\u00f3n de interim management.\n\nSolo entonces podremos aportar asesoramiento experto sobre c\u00f3mo lograr el objetivo deseado. Eso tambi\u00e9n ayudar\u00e1 a definir el perfil del interim manager ideal. El resultado de dicho an\u00e1lisis se pone por escrito.\n\nEn segundo lugar, contactaremos y seleccionaremos ejecutivos adecuados, bas\u00e1ndonos en su carrera, formaci\u00f3n, conocimientos expertos y desempe\u00f1o en entrevistas personales. A continuaci\u00f3n, se presentan los perfiles por escrito \u2013 con referencia individual a su situaci\u00f3n actual y la definici\u00f3n del objetivo. Entonces los ejecutivos que mejor encajen, ser\u00e1n presentados en persona.\n\nEl interim manager podr\u00e1 comenzar a trabajar pocos d\u00edas despu\u00e9s de que se haya tomado la decisi\u00f3n. Al principio de la implantaci\u00f3n, usted, el interim manager y EIM elaborar\u00e1n una especificaci\u00f3n b\u00e1sica de prioridades y objetivos, para establecer claramente el alcance y tipo de tareas que tendr\u00e1n que llevarse a cabo.\n\nDurante la primera reuni\u00f3n de seguimiento se establecer\u00e1n los objetivos finales e hitos con el interim manager, que tendr\u00e1n como resultado un plan de proyecto. Su implementaci\u00f3n est\u00e1 garantizada por un Socio de EIM cualificado, que asumir\u00e1 una funci\u00f3n directiva durante toda la vida del proyecto para facilitar una comunicaci\u00f3n fluida y transparente y una r\u00e1pida soluci\u00f3n de problemas en caso de divergencias.\n\nJunto al progreso del proyecto, se determinar\u00e1 en reuniones peri\u00f3dicas de revisi\u00f3n, si hay que eliminar obst\u00e1culos adicionales para lograr el resultado deseado del proyecto, o si cambios generales en el mercado pueden requerir un ajuste del rumbo del proyecto. En caso de que sea necesario, se puede solicitar apoyo activo en forma de opiniones de expertos desde la red de EIM. Despu\u00e9s de finalizar la misi\u00f3n tendr\u00e1 lugar una reuni\u00f3n recapitulativa. Para m\u00e1s informaci\u00f3n, vea nuestro <strong>proceso de trabajo<\/strong>.\n\n&nbsp;\n\n[\/et_pb_toggle][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; prev_background_color=&#8221;#ffffff&#8221; disabled_on=&#8221;on|on|off&#8221; admin_label=&#8221;Quote Section&#8221; _builder_version=&#8221;3.27.4&#8243; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_start=&#8221;rgba(0,0,0,0)&#8221; background_color_gradient_end=&#8221;#002c3e&#8221; background_color_gradient_direction=&#8221;103deg&#8221; background_color_gradient_start_position=&#8221;51%&#8221; background_color_gradient_end_position=&#8221;51%&#8221; background_color_gradient_overlays_image=&#8221;on&#8221; background_image=&#8221;https:\/\/www.eim.com\/wp-content\/uploads\/2019\/10\/consulting-1.jpeg&#8221; background_position=&#8221;top_center&#8221; min_height=&#8221;700px&#8221; custom_margin=&#8221;0px||||false|false&#8221; top_divider_style=&#8221;slant&#8221; bottom_divider_style=&#8221;slant&#8221; bottom_divider_color=&#8221;#db9300&#8243; bottom_divider_flip=&#8221;horizontal&#8221; saved_tabs=&#8221;all&#8221; fb_built=&#8221;1&#8243; _i=&#8221;2&#8243; _address=&#8221;2&#8243;][et_pb_row column_structure=&#8221;2_5,3_5&#8243; admin_label=&#8221;Quote Area&#8221; _builder_version=&#8221;3.27.4&#8243; max_width=&#8221;2496px&#8221; custom_margin=&#8221;|0%||auto|false|false&#8221; custom_padding=&#8221;|0px|||false|false&#8221; _i=&#8221;0&#8243; _address=&#8221;2.0&#8243;][et_pb_column type=&#8221;2_5&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; _i=&#8221;0&#8243; _address=&#8221;2.0.0&#8243; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;3.27.4&#8243; text_font=&#8221;Montserrat|700|||||||&#8221; text_text_color=&#8221;#ffffff&#8221; text_font_size=&#8221;45px&#8221; text_text_shadow_style=&#8221;preset1&#8243; text_text_shadow_horizontal_length=&#8221;0.09em&#8221; text_text_shadow_blur_strength=&#8221;0.05em&#8221; width=&#8221;100%&#8221; custom_margin=&#8221;47%|0px|||false|false&#8221; custom_padding=&#8221;39px|0px||0px|false|false&#8221; _i=&#8221;0&#8243; _address=&#8221;2.0.0.0&#8243;]\n<p style=\"text-align: left;line-height: 1\">Cada caso es \u00fanico<\/p>\n[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;3_5&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; _i=&#8221;1&#8243; _address=&#8221;2.0.1&#8243; custom_padding__hover=&#8221;|||&#8221;][et_pb_text admin_label=&#8221;Title&#8221; _builder_version=&#8221;3.27.4&#8243; text_font=&#8221;Montserrat||||||||&#8221; text_text_color=&#8221;#ffffff&#8221; text_font_size=&#8221;16px&#8221; text_line_height=&#8221;2em&#8221; link_font=&#8221;||||on|||#f46624|&#8221; link_text_color=&#8221;#333333&#8243; ul_font=&#8221;Montserrat||||||||&#8221; ul_line_height=&#8221;1.8em&#8221; header_font=&#8221;||||||||&#8221; header_2_font=&#8221;Montserrat|600||on|||||&#8221; header_2_text_align=&#8221;center&#8221; header_2_font_size=&#8221;30px&#8221; background_color=&#8221;rgba(0,0,0,0)&#8221; width=&#8221;100%&#8221; max_width=&#8221;80%&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;|21px|35px|96px|false|false&#8221; custom_padding=&#8221;55px|0px|||false|false&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;right&#8221; animation_intensity_slide=&#8221;20%&#8221; animation_starting_opacity=&#8221;100%&#8221; hover_enabled=&#8221;0&#8243; inline_fonts=&#8221;Montserrat&#8221; _i=&#8221;0&#8243; _address=&#8221;2.0.1.0&#8243;]\n\nRecuerde por favor, que cada caso es \u00fanico y normalmente lo mejor es tratarlo personalmente por tel\u00e9fono.\n\nNo se preocupe que le vayamos a vender algo que no necesita.\n\nNo estar\u00edamos mirando atr\u00e1s a m\u00e1s de 30 a\u00f1os de \u00e9xitos \u2013 principalmente basados en recomendaciones boca-a-boca \u2013 si estuvi\u00e9semos persiguiendo el negocio r\u00e1pido. En vez de eso seremos los primeros en dec\u00edrselo en caso de que no tuvi\u00e9semos nada que ofrecerle esta vez, porque sabemos que eso le har\u00e1 confiar todav\u00eda mucho m\u00e1s en nosotros la pr\u00f3xima vez.\n<p style=\"text-align: justify\">Y siempre hay una pr\u00f3xima vez.<\/p>\n\n<ul><\/ul>\n[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; prev_background_color=&#8221;#ffffff&#8221; disabled_on=&#8221;off|off|on&#8221; admin_label=&#8221;Quote Section&#8221; _builder_version=&#8221;3.27.4&#8243; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_start=&#8221;#002c3e&#8221; background_color_gradient_end=&#8221;#002c3e&#8221; background_color_gradient_direction=&#8221;105deg&#8221; background_color_gradient_start_position=&#8221;55%&#8221; background_color_gradient_end_position=&#8221;0%&#8221; background_color_gradient_overlays_image=&#8221;on&#8221; background_enable_image=&#8221;off&#8221; background_position=&#8221;bottom_center&#8221; custom_margin=&#8221;0px||||false|false&#8221; top_divider_style=&#8221;slant&#8221; top_divider_flip=&#8221;horizontal&#8221; bottom_divider_style=&#8221;slant&#8221; bottom_divider_color=&#8221;#db9300&#8243; bottom_divider_flip=&#8221;horizontal&#8221; saved_tabs=&#8221;all&#8221; fb_built=&#8221;1&#8243; _i=&#8221;3&#8243; _address=&#8221;3&#8243;][et_pb_row admin_label=&#8221;Quote Area&#8221; _builder_version=&#8221;3.27.4&#8243; max_width=&#8221;2496px&#8221; custom_margin=&#8221;5%|10%||10%|false|false&#8221; custom_padding=&#8221;||||false|false&#8221; _i=&#8221;0&#8243; _address=&#8221;3.0&#8243;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; _i=&#8221;0&#8243; _address=&#8221;3.0.0&#8243; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;3.27.4&#8243; text_font=&#8221;Montserrat|700|||||||&#8221; text_text_color=&#8221;#ffffff&#8221; text_font_size=&#8221;25px&#8221; custom_margin=&#8221;0.6%|0px|||false|false&#8221; hover_enabled=&#8221;0&#8243; _i=&#8221;0&#8243; _address=&#8221;3.0.0.0&#8243;]\n<p style=\"line-height: 1;text-align: center\">Cada caso es \u00fanico<\/p>\n[\/et_pb_text][et_pb_text admin_label=&#8221;Title&#8221; _builder_version=&#8221;3.27.4&#8243; text_font=&#8221;Montserrat||||||||&#8221; text_text_color=&#8221;#ffffff&#8221; text_font_size=&#8221;16px&#8221; link_font=&#8221;||||on|||#f46624|&#8221; link_text_color=&#8221;#333333&#8243; ul_font=&#8221;Montserrat||||||||&#8221; ul_line_height=&#8221;2em&#8221; header_font=&#8221;||||||||&#8221; header_2_font=&#8221;Montserrat|600||on|||||&#8221; header_2_text_align=&#8221;center&#8221; header_2_font_size=&#8221;30px&#8221; background_color=&#8221;rgba(0,0,0,0)&#8221; max_width=&#8221;879px&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;|29px|6%|-34px|false|false&#8221; custom_padding=&#8221;3%|0.1%|5.8%|0.2%|false|false&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;right&#8221; animation_intensity_slide=&#8221;20%&#8221; animation_starting_opacity=&#8221;100%&#8221; inline_fonts=&#8221;Montserrat&#8221; _i=&#8221;1&#8243; _address=&#8221;3.0.0.1&#8243;]\n\nRecuerde por favor, que cada caso es \u00fanico y normalmente lo mejor es tratarlo personalmente por tel\u00e9fono.\n\nNo se preocupe que le vayamos a vender algo que no necesita.\n\nNo estar\u00edamos mirando atr\u00e1s a m\u00e1s de 30 a\u00f1os de \u00e9xitos \u2013 principalmente basados en recomendaciones boca-a-boca \u2013 si estuvi\u00e9semos persiguiendo el negocio r\u00e1pido. En vez de eso seremos los primeros en dec\u00edrselo en caso de que no tuvi\u00e9semos nada que ofrecerle esta vez, porque sabemos que eso le har\u00e1 confiar todav\u00eda mucho m\u00e1s en nosotros la pr\u00f3xima vez.\n\nY siempre hay una pr\u00f3xima vez.\n\n[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;3.27.4&#8243; background_color=&#8221;#db9300&#8243; custom_margin=&#8221;-0.1%||-0.1%||true|false&#8221; custom_padding=&#8221;37px|||||&#8221; top_divider_color=&#8221;#e09900&#8243; top_divider_flip=&#8221;vertical&#8221; bottom_divider_color=&#8221;#ffffff&#8221; bottom_divider_flip=&#8221;horizontal&#8221; saved_tabs=&#8221;all&#8221; fb_built=&#8221;1&#8243; _i=&#8221;4&#8243; _address=&#8221;4&#8243;][et_pb_row _builder_version=&#8221;3.27.4&#8243; custom_padding=&#8221;60px|||||&#8221; _i=&#8221;0&#8243; _address=&#8221;4.0&#8243;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;3.27.4&#8243; _i=&#8221;0&#8243; _address=&#8221;4.0.0&#8243;][et_pb_text admin_label=&#8221;Title&#8221; _builder_version=&#8221;3.27.4&#8243; text_font=&#8221;||||||||&#8221; text_text_color=&#8221;#ffffff&#8221; header_font=&#8221;Prata||||||||&#8221; header_2_font=&#8221;Montserrat|700|||||||&#8221; header_2_text_align=&#8221;center&#8221; header_2_font_size=&#8221;30px&#8221; custom_margin=&#8221;||5px|&#8221; custom_padding=&#8221;||0px|||&#8221; animation_style=&#8221;fade&#8221; animation_direction=&#8221;top&#8221; animation_duration=&#8221;1350ms&#8221; animation_starting_opacity=&#8221;100%&#8221; inline_fonts=&#8221;Prata,Montserrat&#8221; _i=&#8221;0&#8243; _address=&#8221;4.0.0.0&#8243;]\n<h3 style=\"text-align: center\"><span style=\"font-family: Montserrat;color: #ffffff\">P\u00f3ngase en contacto con nosotros<\/span><\/h3>\n[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_5,3_5,1_5&#8243; _builder_version=&#8221;3.27.4&#8243; custom_padding=&#8221;0px|||||&#8221; _i=&#8221;1&#8243; _address=&#8221;4.1&#8243;][et_pb_column type=&#8221;1_5&#8243; _builder_version=&#8221;3.27.4&#8243; _i=&#8221;0&#8243; _address=&#8221;4.1.0&#8243;][\/et_pb_column][et_pb_column type=&#8221;3_5&#8243; _builder_version=&#8221;3.27.4&#8243; _i=&#8221;1&#8243; _address=&#8221;4.1.1&#8243;][et_pb_text _builder_version=&#8221;3.27.4&#8243; _i=&#8221;0&#8243; _address=&#8221;4.1.1.0&#8243;]\n<p style=\"text-align: center\"><span style=\"color: #ffffff\">Juntos podemos encontrar la soluci\u00f3n que est\u00e1 buscando.<\/span><\/p>\n[\/et_pb_text][et_pb_button button_url=&#8221;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjExOCIsImVuYWJsZV9odG1sIjoib2ZmIn19@&#8221; button_text=&#8221;CONT\u00c1CTENOS&#8221; button_alignment=&#8221;center&#8221; _builder_version=&#8221;3.27.4&#8243; _dynamic_attributes=&#8221;button_url&#8221; background_layout=&#8221;dark&#8221; _i=&#8221;1&#8243; _address=&#8221;4.1.1.1&#8243;][\/et_pb_button][\/et_pb_column][et_pb_column type=&#8221;1_5&#8243; _builder_version=&#8221;3.27.4&#8243; _i=&#8221;2&#8243; _address=&#8221;4.1.2&#8243;][\/et_pb_column][\/et_pb_row][\/et_pb_section]\n\n","protected":false},"excerpt":{"rendered":"<p>Qu\u00e9 hace a EIM \u00fanica y otras preguntas habituales.<br \/>\nSi tiene alguna pregunta, por favor no dude en contactar con una de nuestras oficinas m\u00e1s cercanas.<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-73","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Las preguntas m\u00e1s frecuentes sobre interim management | EIM<\/title>\n<meta name=\"description\" content=\"\u00bfCu\u00e1les son las preguntas m\u00e1s frecuentes que se hace el CEO de una empresa acerca de la posibilidad de apostar por el interim management?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.eim.com\/es\/faq\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"FAQ\" \/>\n<meta property=\"og:description\" content=\"\u00bfCu\u00e1les son las preguntas m\u00e1s frecuentes que se hace el CEO de una empresa acerca de la posibilidad de apostar por el interim management?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.eim.com\/es\/faq\/\" \/>\n<meta property=\"og:site_name\" content=\"Interim Management | EIM Spain\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-12T07:40:27+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.eim.com\\\/es\\\/faq\\\/\",\"url\":\"https:\\\/\\\/www.eim.com\\\/es\\\/faq\\\/\",\"name\":\"Las preguntas m\u00e1s frecuentes sobre interim management | EIM\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eim.com\\\/es\\\/#website\"},\"datePublished\":\"2019-09-12T10:03:17+00:00\",\"dateModified\":\"2026-06-12T07:40:27+00:00\",\"description\":\"\u00bfCu\u00e1les son las preguntas m\u00e1s frecuentes que se hace el CEO de una empresa acerca de la posibilidad de apostar por el interim management?\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.eim.com\\\/es\\\/faq\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.eim.com\\\/es\\\/faq\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.eim.com\\\/es\\\/faq\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.eim.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FAQ\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.eim.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.eim.com\\\/es\\\/\",\"name\":\"Interim Management | EIM Spain\",\"description\":\"El interim manager que su empresa necesita\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.eim.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.eim.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.eim.com\\\/es\\\/#organization\",\"name\":\"EIM Espa\u00f1a \u2013 Executive Interim Management\",\"alternateName\":\"EIM\",\"url\":\"https:\\\/\\\/www.eim.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.eim.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.eim.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/10\\\/2022\\\/01\\\/EIM_logo_positive_HD.png\",\"contentUrl\":\"https:\\\/\\\/www.eim.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/10\\\/2022\\\/01\\\/EIM_logo_positive_HD.png\",\"width\":1920,\"height\":649,\"caption\":\"EIM Espa\u00f1a \u2013 Executive Interim Management\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eim.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Las preguntas m\u00e1s frecuentes sobre interim management | EIM","description":"\u00bfCu\u00e1les son las preguntas m\u00e1s frecuentes que se hace el CEO de una empresa acerca de la posibilidad de apostar por el interim management?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.eim.com\/es\/faq\/","og_locale":"es_ES","og_type":"article","og_title":"FAQ","og_description":"\u00bfCu\u00e1les son las preguntas m\u00e1s frecuentes que se hace el CEO de una empresa acerca de la posibilidad de apostar por el interim management?","og_url":"https:\/\/www.eim.com\/es\/faq\/","og_site_name":"Interim Management | EIM Spain","article_modified_time":"2026-06-12T07:40:27+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.eim.com\/es\/faq\/","url":"https:\/\/www.eim.com\/es\/faq\/","name":"Las preguntas m\u00e1s frecuentes sobre interim management | EIM","isPartOf":{"@id":"https:\/\/www.eim.com\/es\/#website"},"datePublished":"2019-09-12T10:03:17+00:00","dateModified":"2026-06-12T07:40:27+00:00","description":"\u00bfCu\u00e1les son las preguntas m\u00e1s frecuentes que se hace el CEO de una empresa acerca de la posibilidad de apostar por el interim management?","breadcrumb":{"@id":"https:\/\/www.eim.com\/es\/faq\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.eim.com\/es\/faq\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.eim.com\/es\/faq\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.eim.com\/es\/"},{"@type":"ListItem","position":2,"name":"FAQ"}]},{"@type":"WebSite","@id":"https:\/\/www.eim.com\/es\/#website","url":"https:\/\/www.eim.com\/es\/","name":"Interim Management | EIM Spain","description":"El interim manager que su empresa necesita","publisher":{"@id":"https:\/\/www.eim.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.eim.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.eim.com\/es\/#organization","name":"EIM Espa\u00f1a \u2013 Executive Interim Management","alternateName":"EIM","url":"https:\/\/www.eim.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.eim.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.eim.com\/es\/wp-content\/uploads\/sites\/10\/2022\/01\/EIM_logo_positive_HD.png","contentUrl":"https:\/\/www.eim.com\/es\/wp-content\/uploads\/sites\/10\/2022\/01\/EIM_logo_positive_HD.png","width":1920,"height":649,"caption":"EIM Espa\u00f1a \u2013 Executive Interim Management"},"image":{"@id":"https:\/\/www.eim.com\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.eim.com\/es\/wp-json\/wp\/v2\/pages\/73","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eim.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.eim.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.eim.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eim.com\/es\/wp-json\/wp\/v2\/comments?post=73"}],"version-history":[{"count":0,"href":"https:\/\/www.eim.com\/es\/wp-json\/wp\/v2\/pages\/73\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.eim.com\/es\/wp-json\/wp\/v2\/media?parent=73"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}